{"id":20,"count":1,"description":"","link":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/","name":"Engineering Slide","slug":"engineering-slide","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Engineering Slide Archives - H2O Equipment Ltd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Engineering Slide Archives - H2O Equipment Ltd\" \/>\n<meta property=\"og:url\" content=\"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/\" \/>\n<meta property=\"og:site_name\" content=\"H2O Equipment Ltd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/h2oequipment.co.nz\\\/index.php\\\/category\\\/engineering-slide\\\/\",\"url\":\"https:\\\/\\\/h2oequipment.co.nz\\\/index.php\\\/category\\\/engineering-slide\\\/\",\"name\":\"Engineering Slide Archives - H2O Equipment Ltd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/h2oequipment.co.nz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/h2oequipment.co.nz\\\/index.php\\\/category\\\/engineering-slide\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/h2oequipment.co.nz\\\/index.php\\\/category\\\/engineering-slide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/h2oequipment.co.nz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engineering Slide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/h2oequipment.co.nz\\\/#website\",\"url\":\"https:\\\/\\\/h2oequipment.co.nz\\\/\",\"name\":\"H2O Equipment Ltd\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/h2oequipment.co.nz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Engineering Slide Archives - H2O Equipment Ltd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/","og_locale":"en_US","og_type":"article","og_title":"Engineering Slide Archives - H2O Equipment Ltd","og_url":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/","og_site_name":"H2O Equipment Ltd","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/","url":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/","name":"Engineering Slide Archives - H2O Equipment Ltd","isPartOf":{"@id":"https:\/\/h2oequipment.co.nz\/#website"},"breadcrumb":{"@id":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/h2oequipment.co.nz\/index.php\/category\/engineering-slide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/h2oequipment.co.nz\/"},{"@type":"ListItem","position":2,"name":"Engineering Slide"}]},{"@type":"WebSite","@id":"https:\/\/h2oequipment.co.nz\/#website","url":"https:\/\/h2oequipment.co.nz\/","name":"H2O Equipment Ltd","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/h2oequipment.co.nz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/h2oequipment.co.nz\/index.php\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h2oequipment.co.nz\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/h2oequipment.co.nz\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/h2oequipment.co.nz\/index.php\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}